{"id":45919,"date":"2023-06-01T15:53:40","date_gmt":"2023-06-01T18:53:40","guid":{"rendered":"https:\/\/cbr.org.br\/?p=45919"},"modified":"2023-06-01T17:40:53","modified_gmt":"2023-06-01T20:40:53","slug":"cbr-lanca-o-radlex-ferramenta-inovadora-para-a-comunidade-radiologica","status":"publish","type":"post","link":"https:\/\/cbr.org.br\/es\/cbr-lanca-o-radlex-ferramenta-inovadora-para-a-comunidade-radiologica\/","title":{"rendered":"CBR lanza Radlex, una herramienta innovadora para la Comunidad Radiol\u00f3gica"},"content":{"rendered":"<p>El Colegio Brasile\u00f1o de Radiolog\u00eda y Diagn\u00f3stico por Im\u00e1genes (CBR) lanza Radlex en Brasil este jueves (1\u00ba). La herramienta es un l\u00e9xico que re\u00fane m\u00e1s de 47.000 t\u00e9rminos para radi\u00f3logos, con la intenci\u00f3n de llenar un vac\u00edo creado por la creciente digitalizaci\u00f3n de im\u00e1genes, informes de im\u00e1genes y registros m\u00e9dicos. Desarrollado por <em>Sociedad Radiol\u00f3gica de Am\u00e9rica del Norte<\/em> (RSNA), su principal funci\u00f3n es estandarizar la terminolog\u00eda radiol\u00f3gica, y facilitar la comunicaci\u00f3n y miner\u00eda de datos para mejorar la toma de decisiones.<\/p>\n\n\n\n<p>Seg\u00fan el Dr. Otto Wolf Maciel, radi\u00f3logo, miembro del Comit\u00e9 de Informes de CBR, quien particip\u00f3 en el desarrollo de la herramienta junto con el equipo de TI: \u201cCBR jug\u00f3 un papel crucial en este logro y colabor\u00f3 activamente en la traducci\u00f3n completa de RadLex al portugu\u00e9s\u201d. <\/p>\n\n\n\n<p>Con Radlex, los profesionales e investigadores del \u00e1rea podr\u00e1n acceder y consultar t\u00e9rminos estandarizados en su idioma nativo. As\u00ed, aumenta la claridad, la comunicaci\u00f3n y el an\u00e1lisis de datos en radiolog\u00eda, adem\u00e1s de agilizar el proceso y la comprensi\u00f3n de t\u00e9rminos espec\u00edficos.<\/p>\n\n\n\n<p>Adem\u00e1s, la Dra. Otto dice sobre los beneficios que traer\u00e1 la herramienta: \u201cLa implementaci\u00f3n de RadLex en Brasil representa una oportunidad para mejorar la consistencia y precisi\u00f3n de los informes radiol\u00f3gicos, facilitar la comunicaci\u00f3n entre m\u00e9dicos, promover la calidad de los servicios de salud y mejorar la investigaci\u00f3n en radiolog\u00eda\u201d. El m\u00e9dico agreg\u00f3: \u201cAl usar un l\u00e9xico estandarizado como RadLex, aseguramos que todos los t\u00e9rminos utilizados en los informes tengan el mismo significado para todos los m\u00e9dicos, independientemente de su ubicaci\u00f3n o especialidad\u201d.<\/p>\n\n\n\n<p>Cabe mencionar que este fue un trabajo conjunto con la participaci\u00f3n de todo el Comit\u00e9 de Informes, colaboradores y el equipo de TI de CBR.<\/p>\n\n\n\n<p>Radlex estar\u00e1 abierto al p\u00fablico durante tres a seis meses, luego de lo cual solo los miembros del Colegio tendr\u00e1n acceso a la nueva herramienta.<\/p>\n\n\n\n<p><a href=\"https:\/\/bit.ly\/radlex\" target=\"_blank\" rel=\"noreferrer noopener\">Haga clic aqu\u00ed para conocer la herramienta<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El Colegio Brasile\u00f1o de Radiolog\u00eda y Diagn\u00f3stico por Im\u00e1genes (CBR) lanza Radlex en Brasil este jueves (1\u00ba). La herramienta es un l\u00e9xico que re\u00fane m\u00e1s de 47.000 t\u00e9rminos para radi\u00f3logos, con la intenci\u00f3n de llenar un vac\u00edo creado por la creciente digitalizaci\u00f3n de im\u00e1genes, informes de im\u00e1genes y registros m\u00e9dicos. Desarrollado por la Sociedad Radiol\u00f3gica del Norte... <a href=\"https:\/\/cbr.org.br\/es\/cbr-lanca-o-radlex-ferramenta-inovadora-para-a-comunidade-radiologica\/\">Sigue leyendo<\/a><\/p>","protected":false},"author":24,"featured_media":45921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[50,96,328],"class_list":["post-45919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional","tag-cbr","tag-radiologia","tag-tecnologia"],"acf":[],"_links":{"self":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts\/45919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/comments?post=45919"}],"version-history":[{"count":2,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts\/45919\/revisions"}],"predecessor-version":[{"id":45933,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts\/45919\/revisions\/45933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/media\/45921"}],"wp:attachment":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/media?parent=45919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/categories?post=45919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/tags?post=45919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}