{"id":46167,"date":"2023-07-07T12:43:56","date_gmt":"2023-07-07T15:43:56","guid":{"rendered":"https:\/\/cbr.org.br\/?p=46167"},"modified":"2023-07-07T12:43:57","modified_gmt":"2023-07-07T15:43:57","slug":"edital-de-convocacao-para-assembleia-geral-extraordinaria-do-colegio-brasileiro-de-radiologia-diagnostico-por-imagem","status":"publish","type":"post","link":"https:\/\/cbr.org.br\/es\/edital-de-convocacao-para-assembleia-geral-extraordinaria-do-colegio-brasileiro-de-radiologia-diagnostico-por-imagem\/","title":{"rendered":"CONVOCATORIA DE ASAMBLEA GENERAL EXTRAORDINARIA DEL COLEGIO BRASILE\u00d1O DE RADIOLOG\u00cdA Y DIAGN\u00d3STICO POR IM\u00c1GENES"},"content":{"rendered":"<p>Por este Aviso, se invita a los Asociados del Colegio Brasile\u00f1o de Radiolog\u00eda y Diagn\u00f3stico por Imagen \u2013 CBR a reunirse para el <strong>ASAMBLEA GENERAL EXTRAORDINARIA<\/strong>, que se realizar\u00e1 en modalidad Virtual, el d\u00eda 9 de octubre de 2023, a las 18:00 horas (dieciocho horas), en primera convocatoria, cuando sea necesaria la presencia de al menos 50 (cincuenta) miembros asociados, y a las 6 :30 horas (dieciocho horas) con treinta minutos), en segunda y \u00faltima convocatoria, cuando se celebre con cualquier n\u00famero de personas presentes, a trav\u00e9s de la plataforma <strong>ZOOM<\/strong>, cuyo enlace de acceso ser\u00e1 remitido a todos con 24 horas (veinticuatro horas) de antelaci\u00f3n a la celebraci\u00f3n de la Junta, a fin de deliberar sobre el siguiente Orden del D\u00eda:<\/p>\n\n\n\n<p><strong>A)<\/strong> Modificaci\u00f3n de los art\u00edculos 3, 4, 5, 6, 13, 14, 20, 36, 38, 40, 42, 46, 52, 55, 58, 59, 65, 68, 69, 71, 72, 76, 77, 78 , 79, 80, 81, 83, 84, 86 y 88 del Estatuto del Colegio Brasile\u00f1o de Radiolog\u00eda \u2013 CBR, propuesto por la Direcci\u00f3n Ejecutiva, en los t\u00e9rminos del art\u00edculo 50, inciso 4, p\u00e1rrafos 3, 4, 5 y 6 de la estatutos;<\/p>\n\n\n\n<p><strong>B)<\/strong> Temas generales; En cuanto a las reglas para reformar los Estatutos Sociales, esta Convocatoria se publica 90 d\u00edas antes de la fecha de la Asamblea (art. 50, \u00a7 4); se fija un plazo de 15 (quince) d\u00edas para la presentaci\u00f3n de propuestas relativas a las modificaciones (art. 50, \u00a7 5); transcurrido el plazo de 15 (quince) d\u00edas y recogidas las eventuales sugerencias, la redacci\u00f3n final de los dispositivos que pretendan ser modificados ser\u00e1 elaborada por la CBR, en el plazo m\u00e1ximo de 30 (treinta) d\u00edas (art. 50, p\u00e1rrafo 4); la redacci\u00f3n final del estatuto ser\u00e1 comunicada a todos dentro de los 10 (diez) d\u00edas anteriores a la celebraci\u00f3n de la Asamblea (art. 50, \u00a7 5). Y, a pedido de la Direcci\u00f3n Ejecutiva, publicamos este aviso en el \u00f3rgano oficial de la CBR, para conocimiento de todos.<\/p>\n\n\n\n<p>S\u00e3o Paulo, 7 de julio de 2023.<\/p>\n\n\n\n<p>Colegio Brasile\u00f1o de Radiolog\u00eda e Im\u00e1genes de Diagn\u00f3stico.<br><\/p>\n\n\n\n<p>Dr. Cibeles Alves de Carvalho<br>Presidente del Colegio Brasile\u00f1o de Radiolog\u00eda y Diagn\u00f3stico por Im\u00e1genes<\/p>","protected":false},"excerpt":{"rendered":"<p>Por este Aviso, se invita a los Asociados del Colegio Brasile\u00f1o de Radiolog\u00eda y Diagn\u00f3stico por Imagen \u2013 CBR a reunirse para la ASAMBLEA GENERAL EXTRAORDINARIA, que se realizar\u00e1 en modalidad Virtual, el d\u00eda 9 de octubre de 2023, a las 18:00 horas (dieciocho horas), en primera convocatoria, cuando sea necesaria la presencia de al menos 50\u2026 <a href=\"https:\/\/cbr.org.br\/es\/edital-de-convocacao-para-assembleia-geral-extraordinaria-do-colegio-brasileiro-de-radiologia-diagnostico-por-imagem\/\">Sigue leyendo<\/a><\/p>","protected":false},"author":24,"featured_media":46168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[464,50,43],"class_list":["post-46167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional","tag-assembleia-geral","tag-cbr","tag-colegio-brasileiro-de-radiologia-e-diagnostico-por-imagem"],"acf":[],"_links":{"self":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts\/46167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/comments?post=46167"}],"version-history":[{"count":2,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts\/46167\/revisions"}],"predecessor-version":[{"id":46170,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/posts\/46167\/revisions\/46170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/media\/46168"}],"wp:attachment":[{"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/media?parent=46167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/categories?post=46167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbr.org.br\/es\/wp-json\/wp\/v2\/tags?post=46167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}